{"id":37,"date":"2020-11-10T09:02:27","date_gmt":"2020-11-10T09:02:27","guid":{"rendered":"https:\/\/hostechpk.com\/tutorials\/?page_id=37"},"modified":"2020-12-28T10:25:46","modified_gmt":"2020-12-28T10:25:46","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/hostechpk.com\/tutorials\/contact-us\/","title":{"rendered":"Contact Us"},"content":{"rendered":"<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f608-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/tutorials\/wp-json\/wp\/v2\/pages\/37#wpcf7-f608-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"608\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.3\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f608-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<p><label> Your Name<br \/>\n    <span class=\"wpcf7-form-control-wrap your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Your Email<br \/>\n    <span class=\"wpcf7-form-control-wrap your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Subject<br \/>\n    <span class=\"wpcf7-form-control-wrap your-subject\"><input type=\"text\" name=\"your-subject\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Your message (optional)<br \/>\n    <span class=\"wpcf7-form-control-wrap your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\"><\/textarea><\/span> <\/label><\/p>\n<p><input type=\"submit\" value=\"Submit\" class=\"wpcf7-form-control wpcf7-submit\" \/><\/p>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hostechpk.com\/tutorials\/contact-us\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact Us -\" \/>\n<meta property=\"og:description\" content=\"&nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hostechpk.com\/tutorials\/contact-us\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-28T10:25:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\">\n\t<meta name=\"twitter:data1\" content=\"admin\">\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data2\" content=\"0 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hostechpk.com\/tutorials\/#website\",\"url\":\"https:\/\/hostechpk.com\/tutorials\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/hostechpk.com\/tutorials\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hostechpk.com\/tutorials\/contact-us\/#webpage\",\"url\":\"https:\/\/hostechpk.com\/tutorials\/contact-us\/\",\"name\":\"Contact Us -\",\"isPartOf\":{\"@id\":\"https:\/\/hostechpk.com\/tutorials\/#website\"},\"datePublished\":\"2020-11-10T09:02:27+00:00\",\"dateModified\":\"2020-12-28T10:25:46+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hostechpk.com\/tutorials\/contact-us\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/hostechpk.com\/tutorials\/wp-json\/wp\/v2\/pages\/37"}],"collection":[{"href":"https:\/\/hostechpk.com\/tutorials\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hostechpk.com\/tutorials\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hostechpk.com\/tutorials\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hostechpk.com\/tutorials\/wp-json\/wp\/v2\/comments?post=37"}],"version-history":[{"count":54,"href":"https:\/\/hostechpk.com\/tutorials\/wp-json\/wp\/v2\/pages\/37\/revisions"}],"predecessor-version":[{"id":612,"href":"https:\/\/hostechpk.com\/tutorials\/wp-json\/wp\/v2\/pages\/37\/revisions\/612"}],"wp:attachment":[{"href":"https:\/\/hostechpk.com\/tutorials\/wp-json\/wp\/v2\/media?parent=37"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}